{"id":10463,"date":"2025-12-03T15:12:46","date_gmt":"2025-12-03T20:12:46","guid":{"rendered":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/?p=10463"},"modified":"2026-03-18T19:33:30","modified_gmt":"2026-03-19T00:33:30","slug":"oferta-academica-2026-1","status":"publish","type":"post","link":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/noticias-de-interes\/oferta-academica-2026-1\/","title":{"rendered":"Oferta acad\u00e9mica 2026 &#8211; 1"},"content":{"rendered":"\n<p><span class=\"post-content__span\"> A continuaci\u00f3n se presente la oferta&nbsp;acad\u00e9mica&nbsp;de la Maestr\u00eda en Matem\u00e1tica, con el fin de que puedan realizar la solicitud de cursos que desean tomar el pr\u00f3ximo semestre&nbsp;acad\u00e9mico 2026-1. Para realizar la matr\u00edcula correspondiente, se solicita amablemente informar por medio del correo electr\u00f3nico&nbsp;<a href=\"mailto:maestriamatematica@utp.edu.co\">maestriamatematica@utp.edu.co<\/a>&nbsp;los cursos a tomar a m\u00e1s tardar el d\u00eda<strong>&nbsp;05 de marzo de 2026<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Nombre del curso<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Componente<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Docente<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fecha de inicio<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Horario<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Sal\u00f3n<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">FA174 Ecuaciones Diferenciales Ordinarias<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fundamentaci\u00f3n<\/td><td class=\"has-text-align-center\" data-align=\"center\">Dr. Pedro Pablo C\u00e1rdenas Alzate<\/td><td class=\"has-text-align-center\" data-align=\"center\">07 de marzo de 2026<\/td><td class=\"has-text-align-center\" data-align=\"center\">s\u00e1bado de 09:00 a.m. a 12:00 m.<\/td><td class=\"has-text-align-center\" data-align=\"center\">15C-402<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">FA184 Topolog\u00eda General<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fundamentaci\u00f3n<\/td><td class=\"has-text-align-center\" data-align=\"center\">Dr. Herman Jos\u00e9 Serrano L\u00f3pez<\/td><td class=\"has-text-align-center\" data-align=\"center\">06 de marzo de 2026<\/td><td class=\"has-text-align-center\" data-align=\"center\">viernes 06:00 p.m. a 09:00 p.m.<\/td><td class=\"has-text-align-center\" data-align=\"center\">15C-402<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">FA2Y4 An\u00e1lisis Fraccionario<\/td><td class=\"has-text-align-center\" data-align=\"center\">Profundizaci\u00f3n<\/td><td class=\"has-text-align-center\" data-align=\"center\">Dr. Fabi\u00e1n Toledo S\u00e1nchez<\/td><td class=\"has-text-align-center\" data-align=\"center\">07 de marzo de 2026<\/td><td class=\"has-text-align-center\" data-align=\"center\">s\u00e1bado de 02:00 p.m. a 05:00 p.m.<\/td><td class=\"has-text-align-center\" data-align=\"center\">15C-312<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">FA234 Teor\u00eda de Transformadas<\/td><td class=\"has-text-align-center\" data-align=\"center\">Profundizaci\u00f3n<\/td><td class=\"has-text-align-center\" data-align=\"center\">Dr. Jaime Navarro Fuentes<\/td><td class=\"has-text-align-center\" data-align=\"center\">07 de marzo de 2026<\/td><td class=\"has-text-align-center\" data-align=\"center\">s\u00e1bado de 08:00 a.m. a 11:00 a.m.<\/td><td class=\"has-text-align-center\" data-align=\"center\">15C-208<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci\u00f3n se presente la oferta&nbsp;acad\u00e9mica&nbsp;de la Maestr\u00eda en Matem\u00e1tica, con el fin de que puedan realizar la solicitud de cursos que desean tomar el pr\u00f3ximo semestre&nbsp;acad\u00e9mico 2026-1. Para realizar [&#8230;]<\/p>\n","protected":false},"author":27,"featured_media":10475,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-10463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-interes"],"_links":{"self":[{"href":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/wp-json\/wp\/v2\/posts\/10463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/wp-json\/wp\/v2\/comments?post=10463"}],"version-history":[{"count":22,"href":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/wp-json\/wp\/v2\/posts\/10463\/revisions"}],"predecessor-version":[{"id":10503,"href":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/wp-json\/wp\/v2\/posts\/10463\/revisions\/10503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/wp-json\/wp\/v2\/media\/10475"}],"wp:attachment":[{"href":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/wp-json\/wp\/v2\/media?parent=10463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/wp-json\/wp\/v2\/categories?post=10463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/basicas.utp.edu.co\/maestria-en-matematicas\/wp-json\/wp\/v2\/tags?post=10463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}